{"id":180,"date":"2018-11-07T17:53:48","date_gmt":"2018-11-07T15:53:48","guid":{"rendered":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/?p=180"},"modified":"2021-03-01T18:51:37","modified_gmt":"2021-03-01T16:51:37","slug":"extirpacion-del-pancreas-insuficiencia-pancreatica","status":"publish","type":"post","link":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/","title":{"rendered":"\u00bfCu\u00e1les son las consecuencias tras la extirpaci\u00f3n parcial o total del p\u00e1ncreas? La insuficiencia pancre\u00e1tica"},"content":{"rendered":"<p><a href=\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/pancreas-funcion-enferma\/\">El <strong>p\u00e1ncreas<\/strong><\/a> presenta varias funciones, entre las que se encuentran: la <strong>funci\u00f3n de control de los niveles de az\u00facar en sangre<\/strong> (<strong>funci\u00f3n endocrina<\/strong>) <strong>y la funci\u00f3n digestiva<\/strong> (<strong>funci\u00f3n exocrina<\/strong>). La <strong>funci\u00f3n del p\u00e1ncreas<\/strong> se reparte de forma asim\u00e9trica a lo largo de toda la gl\u00e1ndula; as\u00ed, en la <strong>cabeza del p\u00e1ncreas<\/strong> <strong>predomina la funci\u00f3n exocrina<\/strong>, mientras que en la <strong>en el cuerpo y la cola predomina la funci\u00f3n endocrina<\/strong>. Esto no significa necesariamente que, tras una intervenci\u00f3n quir\u00fargica de extirpaci\u00f3n de la cabeza o del cuerpo y la cola, el paciente vaya a presentar irremediablemente una <strong>insuficiencia pancre\u00e1tica<\/strong>. Sin embargo, <strong>tras la extirpaci\u00f3n del p\u00e1ncreas (parcial o <a href=\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpar-completamente-el-pancreas\/\">total<\/a>)<\/strong>,<a href=\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/calidad-de-vida-cirugia-del-pancreas\/\"><strong> una o ambas funciones pueden verse comprometidas<\/strong><\/a>.<\/p>\n<p><!--more--><\/p>\n<p>Si el deterioro de una de las <strong>funciones del p\u00e1ncreas<\/strong> alcanza cierto nivel, hablaremos de <strong>insuficiencia pancre\u00e1tica endocrina o exocrina<\/strong>. Ante la presencia de una <strong>insuficiencia pancre\u00e1tica<\/strong>, el paciente puede presentar manifestaciones cl\u00ednicas que afectar\u00e1n de forma importante su calidad de vida.<\/p>\n<h2><strong>Insuficiencia pancre\u00e1tica exocrina<\/strong><\/h2>\n<p>La <strong>insuficiencia pancre\u00e1tica exocrina<\/strong> <strong>se produce cuando la producci\u00f3n de los enzimas digestivos<\/strong> (principalmente <a href=\"https:\/\/es.wikipedia.org\/wiki\/Amilasa\" target=\"_blank\" rel=\"noopener noreferrer\"><em>amilasa<\/em><\/a>, <a href=\"https:\/\/es.wikipedia.org\/wiki\/Tripsina\" target=\"_blank\" rel=\"noopener noreferrer\"><em>tripsina<\/em><\/a> y <a href=\"https:\/\/es.wikipedia.org\/wiki\/Lipasa\" target=\"_blank\" rel=\"noopener noreferrer\"><em>lipasa<\/em><\/a>) <strong>es insuficiente para que el paciente pueda llevar a cabo una correcta digesti\u00f3n<\/strong> tras una ingesta alimentaria normal. Estos enzimas tienen como finalidad el convertir las grasas, prote\u00ednas y carbohidratos de la dieta en peque\u00f1as part\u00edculas que pueden ser absorbidas por el intestino. Un paciente con <strong>insuficiencia pancre\u00e1tica exocrina<\/strong> presenta una deficiente digesti\u00f3n de los alimentos dentro del intestino, circunstancia que puede provocar una sintomatolog\u00eda variada. Por un lado, dado que los enzimas no han podido preparar el alimento para la absorci\u00f3n intestinal, esta se ve muy disminuida en comparaci\u00f3n con la situaci\u00f3n normal. Como consecuencia, el paciente pierde peso, incluso llevando a cabo una <strong>dieta hipercal\u00f3rica<\/strong>. \u00c9sta p\u00e9rdida de peso conduce a una desnutrici\u00f3n que, si es importante, puede afectar en mayor o menor medida a otros sistemas del cuerpo, e incluso al sistema inmunol\u00f3gico. Por otra parte, \u00a0la acumulaci\u00f3n de alimento sin digerir en el tracto digestivo favorece el sobrecrecimiento bacteriano y la presencia de flatulencia importante. Finalmente, dado que elementos de la dieta como las grasas no se han podido absorber correctamente, el paciente presenta una diarrea caracter\u00edstica con un alto contenido en grasa que se denomina esteatorrea. Afortunadamente, hoy en d\u00eda disponemos de complejos enzim\u00e1ticos para el tratamiento de la <strong>insuficiencia pancre\u00e1tica exocrina<\/strong>. Para la m\u00e1xima eficacia, este tratamiento debe tomarse durante las comidas y en ocasiones deben asociarse f\u00e1rmacos que inhiben la producci\u00f3n de \u00e1cido en el est\u00f3mago para evitar su degradaci\u00f3n tras la ingesta.<\/p>\n<h2><strong>Insuficiencia pancre\u00e1tica endocrina<\/strong><\/h2>\n<p>En cuanto a la <strong>insuficiencia pancre\u00e1tica endocrina<\/strong>, \u00e9sta se caracteriza por la aparici\u00f3n de una <strong>diabetes tras la intervenci\u00f3n quir\u00fargica<\/strong>. En funci\u00f3n de la <strong>p\u00e9rdida de tejido endocrino pancre\u00e1tico<\/strong>, el paciente puede necesitar tratamiento con antidiab\u00e9ticos orales o incluso con insulina subcut\u00e1nea. Adem\u00e1s, los pacientes en los que, por distintas circunstancias, se les ha tenido que <a href=\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpar-completamente-el-pancreas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>extirpar completamente el p\u00e1ncreas<\/strong> (<strong>pancreatectom\u00eda total<\/strong>)<\/a>, van a presentar un tipo especial de diabetes que se caracterizar\u00e1 no solamente por la ausencia total de insulina, sino tambi\u00e9n por la ausencia de otras hormonas contrarreguladoras (por ejemplo, el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Glucag%C3%B3n\" target=\"_blank\" rel=\"noopener noreferrer\"><em>glucag\u00f3n<\/em><\/a>). \u00a0Este tipo de <strong>diabetes<\/strong> se caracteriza por ser de muy dif\u00edcil control y especialmente por la presencia de frecuentes episodios de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Hipoglucemia\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>hipoglicemia<\/strong><\/a> que, si no son detectados a tiempo por el paciente y sus familiares, pueden presentar serias consecuencias.<\/p>\n<h2><strong>M\u00e9dicos especialistas y un correcto tratamiento, mejor calidad de vida<\/strong><\/h2>\n<p>En ambos casos de <strong>insuficiencia pancre\u00e1tica<\/strong>, el tratamiento debe llevarse a cabo por m\u00e9dicos especialistas (<a href=\"https:\/\/www.barnaclinic.com\/es\/especialidades\/108\/gastroenterologia\" target=\"_blank\" rel=\"noopener noreferrer\">gastroenter\u00f3logos<\/a> y <a href=\"https:\/\/www.barnaclinic.com\/es\/especialidades\/39\/endocrinologia-y-nutricion\" target=\"_blank\" rel=\"noopener noreferrer\">endocrin\u00f3logos<\/a>, respectivamente), con el objetivo de reducir al m\u00e1ximo las consecuencias del <strong>d\u00e9ficit de funci\u00f3n pancre\u00e1tica<\/strong>, que puede comportar consecuencias especialmente a largo plazo. Varios estudios han tratado la <strong>calidad de vida de los pacientes con la insuficiencia pancre\u00e1tica despu\u00e9s de una extirpaci\u00f3n quir\u00fargica del p\u00e1ncreas<\/strong>, concluyendo que, aunque est\u00e9 seriamente afectada tras la cirug\u00eda, puede mejorar de forma significativa e incluso equipararse a la de la poblaci\u00f3n general con un correcto tratamiento.<\/p>\n<blockquote>\n<h4><strong>Varios estudios han tratado la calidad de vida de los pacientes con la insuficiencia pancre\u00e1tica despu\u00e9s de una extirpaci\u00f3n quir\u00fargica del p\u00e1ncreas, concluyendo que, aunque est\u00e9 seriamente afectada tras la cirug\u00eda, puede mejorar de forma significativa e incluso equipararse a la de la poblaci\u00f3n general con un correcto tratamiento<\/strong><\/h4>\n<\/blockquote>\n<hr \/>\n<div id=\"estoy-interesado\" class=\"destacat-site\">\n<h1 style=\"padding-left: 15px; padding-right: 15px;\" align=\"center\"><span style=\"color: white;\">\u00bfQUIERES CONTACTAR CON NUESTRO EQUIPO DE PROFESIONALES DE CIRUG\u00cdA DEL P\u00c1NCREAS?<\/span><\/h1>\n<p style=\"padding-left: 30px; padding-right: 20px;\" align=\"center\"><a class=\"button\" href=\"https:\/\/www.barnaclinic.com\/es\/solicitar-cita\/?especialidad=151\" target=\"_blank\" rel=\"noopener noreferrer\">PEDIR CITA<\/a>\u00a0|\u00a0<a class=\"button\" style=\"padding-left: 30px; padding-right: 20px;\" href=\"https:\/\/www.barnaclinic.com\/es\/solicitar-televisita\/?especialidad=151\" target=\"_blank;\">SOLICITAR TELEVISITA<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El p\u00e1ncreas presenta varias funciones, entre las que se encuentran: la funci\u00f3n de control de los niveles de az\u00facar en sangre (funci\u00f3n endocrina) y la funci\u00f3n digestiva (funci\u00f3n exocrina). La funci\u00f3n del p\u00e1ncreas se reparte de forma asim\u00e9trica a lo largo de toda la gl\u00e1ndula; as\u00ed, en la cabeza del p\u00e1ncreas predomina la funci\u00f3n exocrina, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10,21,9],"tags":[29,36,52,54,5,34,53],"class_list":["post-180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cancer-de-pancreas","category-cirugia","category-lesiones-del-pancreas","category-pancreatitis","tag-diabetes","tag-extirpacion","tag-insuficiencia","tag-insuficiencia-pancreatica","tag-pancreas","tag-pancreatectomia","tag-pancreatica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Consecuencias tras la extirpaci\u00f3n del p\u00e1ncreas: Insuficiencia pancre\u00e1tica<\/title>\n<meta name=\"description\" content=\"Tras una cirug\u00eda de extirpaci\u00f3n del p\u00e1ncreas, el paciente puede presentar insuficiencia pancre\u00e1tica, afectando a una o varias de las funciones del mismo...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consecuencias tras la extirpaci\u00f3n del p\u00e1ncreas: Insuficiencia pancre\u00e1tica\" \/>\n<meta property=\"og:description\" content=\"Tras una cirug\u00eda de extirpaci\u00f3n del p\u00e1ncreas, el paciente puede presentar insuficiencia pancre\u00e1tica, afectando a una o varias de las funciones del mismo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Cirug\u00eda del P\u00e1ncreas\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-07T15:53:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-01T16:51:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-content\/uploads\/sites\/5\/insuficiencia-pancreatica-extirpacion-pancreas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"barnacl\u00ednic+\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"barnacl\u00ednic+\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/\",\"url\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/\",\"name\":\"Consecuencias tras la extirpaci\u00f3n del p\u00e1ncreas: Insuficiencia pancre\u00e1tica\",\"isPartOf\":{\"@id\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#website\"},\"datePublished\":\"2018-11-07T15:53:48+00:00\",\"dateModified\":\"2021-03-01T16:51:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#\/schema\/person\/062c0219c54bbf07163f34494da33e17\"},\"description\":\"Tras una cirug\u00eda de extirpaci\u00f3n del p\u00e1ncreas, el paciente puede presentar insuficiencia pancre\u00e1tica, afectando a una o varias de las funciones del mismo...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1les son las consecuencias tras la extirpaci\u00f3n parcial o total del p\u00e1ncreas? La insuficiencia pancre\u00e1tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#website\",\"url\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/\",\"name\":\"Blog de Cirug\u00eda del P\u00e1ncreas\",\"description\":\"En este blog ofrece informaci\u00f3n sobre cirug\u00eda del p\u00e1ncreas el Dr. Santiago S\u00e1nchez Cab\u00fas, experto del servicio de Cirug\u00eda General y Hepatobiliopancre\u00e1tica de barnacl\u00ednic+\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#\/schema\/person\/062c0219c54bbf07163f34494da33e17\",\"name\":\"barnacl\u00ednic+\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d6a36f6e326a816ac635808864feed8bc381527908e45406660f6ee6ebffee1b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d6a36f6e326a816ac635808864feed8bc381527908e45406660f6ee6ebffee1b?s=96&d=mm&r=g\",\"caption\":\"barnacl\u00ednic+\"},\"url\":\"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/author\/alex\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consecuencias tras la extirpaci\u00f3n del p\u00e1ncreas: Insuficiencia pancre\u00e1tica","description":"Tras una cirug\u00eda de extirpaci\u00f3n del p\u00e1ncreas, el paciente puede presentar insuficiencia pancre\u00e1tica, afectando a una o varias de las funciones del mismo...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/","og_locale":"es_ES","og_type":"article","og_title":"Consecuencias tras la extirpaci\u00f3n del p\u00e1ncreas: Insuficiencia pancre\u00e1tica","og_description":"Tras una cirug\u00eda de extirpaci\u00f3n del p\u00e1ncreas, el paciente puede presentar insuficiencia pancre\u00e1tica, afectando a una o varias de las funciones del mismo...","og_url":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/","og_site_name":"Blog de Cirug\u00eda del P\u00e1ncreas","article_published_time":"2018-11-07T15:53:48+00:00","article_modified_time":"2021-03-01T16:51:37+00:00","og_image":[{"width":800,"height":350,"url":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-content\/uploads\/sites\/5\/insuficiencia-pancreatica-extirpacion-pancreas.jpg","type":"image\/jpeg"}],"author":"barnacl\u00ednic+","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"barnacl\u00ednic+","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/","url":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/","name":"Consecuencias tras la extirpaci\u00f3n del p\u00e1ncreas: Insuficiencia pancre\u00e1tica","isPartOf":{"@id":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#website"},"datePublished":"2018-11-07T15:53:48+00:00","dateModified":"2021-03-01T16:51:37+00:00","author":{"@id":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#\/schema\/person\/062c0219c54bbf07163f34494da33e17"},"description":"Tras una cirug\u00eda de extirpaci\u00f3n del p\u00e1ncreas, el paciente puede presentar insuficiencia pancre\u00e1tica, afectando a una o varias de las funciones del mismo...","breadcrumb":{"@id":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/extirpacion-del-pancreas-insuficiencia-pancreatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1les son las consecuencias tras la extirpaci\u00f3n parcial o total del p\u00e1ncreas? La insuficiencia pancre\u00e1tica"}]},{"@type":"WebSite","@id":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#website","url":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/","name":"Blog de Cirug\u00eda del P\u00e1ncreas","description":"En este blog ofrece informaci\u00f3n sobre cirug\u00eda del p\u00e1ncreas el Dr. Santiago S\u00e1nchez Cab\u00fas, experto del servicio de Cirug\u00eda General y Hepatobiliopancre\u00e1tica de barnacl\u00ednic+","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#\/schema\/person\/062c0219c54bbf07163f34494da33e17","name":"barnacl\u00ednic+","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d6a36f6e326a816ac635808864feed8bc381527908e45406660f6ee6ebffee1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6a36f6e326a816ac635808864feed8bc381527908e45406660f6ee6ebffee1b?s=96&d=mm&r=g","caption":"barnacl\u00ednic+"},"url":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/posts\/180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/comments?post=180"}],"version-history":[{"count":2,"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/posts\/180\/revisions"}],"predecessor-version":[{"id":397,"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/posts\/180\/revisions\/397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/media\/181"}],"wp:attachment":[{"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/media?parent=180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/categories?post=180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barnaclinic.com\/blog\/cirugia-del-pancreas\/wp-json\/wp\/v2\/tags?post=180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}